{"id":21443,"date":"2026-03-03T08:09:46","date_gmt":"2026-03-03T08:09:46","guid":{"rendered":"https:\/\/danisense.com\/products\/dr10000im\/"},"modified":"2026-07-15T05:15:56","modified_gmt":"2026-07-15T05:15:56","slug":"dr10000im","status":"publish","type":"danisense_product","link":"https:\/\/danisense.com\/de\/produkte\/dr10000im\/","title":{"rendered":"DR10000IM"},"content":{"rendered":"<p>Hochpr\u00e4ziser Gleichstromwandler (DCCT), der bis zu 11000 A Stromst\u00e4rke und kontinuierlich 10000 A Stromst\u00e4rke mit einem Linearit\u00e4tsfehler von weniger als 1 ppm misst.<\/p>\n<p>Basierend auf der ultrastabilen Danisense Closed-Loop-Flux-Gate-Technologie verf\u00fcgt der DR10000IM \u00fcber einen sehr geringen Offset und eine extrem niedrige Drift.<\/p>\n<p>Das DR10000IM-System besteht aus einem Sensorkopf und einer netzbetriebenen Steuereinheit, die \u00fcber ein Kabel mit verschiedenen L\u00e4ngenoptionen verbunden sind.<\/p>\n<p>Es bietet eine hohe Aufl\u00f6sung f\u00fcr eine pr\u00e4zise \u00dcberwachung, eine zuverl\u00e4ssige und konsistente Leistung und ein robustes Design f\u00fcr eine lange Lebensdauer.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hochpr\u00e4ziser Gleichstromwandler (DCCT), der bis zu 11000 A Stromst\u00e4rke und kontinuierlich 10000 A Stromst\u00e4rke mit einem Linearit\u00e4tsfehler von weniger als 1 ppm misst. Basierend auf der ultrastabilen Danisense Closed-Loop-Flux-Gate-Technologie verf\u00fcgt der DR10000IM \u00fcber einen sehr geringen Offset und eine extrem niedrige Drift. Das DR10000IM-System besteht aus einem Sensorkopf und einer netzbetriebenen Steuereinheit, die \u00fcber ein [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":15844,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"output_type":[251],"class_list":["post-21443","danisense_product","type-danisense_product","status-publish","has-post-thumbnail","hentry","output_type-dr-series"],"_links":{"self":[{"href":"https:\/\/danisense.com\/de\/wp-json\/wp\/v2\/danisense_product\/21443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/danisense.com\/de\/wp-json\/wp\/v2\/danisense_product"}],"about":[{"href":"https:\/\/danisense.com\/de\/wp-json\/wp\/v2\/types\/danisense_product"}],"author":[{"embeddable":true,"href":"https:\/\/danisense.com\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/danisense.com\/de\/wp-json\/wp\/v2\/comments?post=21443"}],"version-history":[{"count":0,"href":"https:\/\/danisense.com\/de\/wp-json\/wp\/v2\/danisense_product\/21443\/revisions"}],"wp:attachment":[{"href":"https:\/\/danisense.com\/de\/wp-json\/wp\/v2\/media?parent=21443"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/danisense.com\/de\/wp-json\/wp\/v2\/tags?post=21443"},{"taxonomy":"output_type","embeddable":true,"href":"https:\/\/danisense.com\/de\/wp-json\/wp\/v2\/output_type?post=21443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}